{"id":1486,"date":"2015-07-29T07:00:59","date_gmt":"2015-07-29T07:00:59","guid":{"rendered":"http:\/\/blogs.magicjudges.org\/rulestips-es\/?p=1486"},"modified":"2015-07-28T17:37:17","modified_gmt":"2015-07-28T17:37:17","slug":"dominio-de-hechizos-como-funciona","status":"publish","type":"post","link":"https:\/\/blogs.magicjudges.org\/rulestips-es\/dominio-de-hechizos-como-funciona\/","title":{"rendered":"Dominio de Hechizos: \u00bfComo funciona?"},"content":{"rendered":"<p style=\"text-align: justify\"><p><img  style='float:right'  class='lems-mtg-cardimg' src='http:\/\/gatherer.wizards.com\/Handlers\/Image.ashx?size=small&type=card&name=Experimentos oscuros'><\/p><\/p>\n<p style=\"text-align: justify\">\u00a1Bienvenidos! Hoy le daremos unas vueltas al <em>Dominio de hechizos<\/em>, una de las \u00a0nuevas mec\u00e1nicas de Or\u00edgenes. El hecho de que se encuentre escrito en cursiva ya nos indica algo: no significa nada durante una partida. Las &#8220;habilidades&#8221; escritas en cursiva son una forma de agrupar habilidades que hacen cosas parecidas o se disparan de la misma manera. En este caso, <em>Domino de hechizos<\/em> nos alerta del hecho de que si tenemos dos o mas instant\u00e1neos o conjuros en el cementerio, existe un efecto extra. Sabiendo esto, sabemos que cada habilidad precedida con <em>Dominio de hechizos<\/em>\u00a0podr\u00e1 hacer algo diferente.<\/p>\n<p style=\"text-align: justify\">Como un hechizo con <em>Dominio de hechizos<\/em> se encuentra en la pila cuando comprueba si se aplica la habilidad extra, no contar\u00e1 como uno de los hechizos en el cementerio requeridos. Las cartas con <em>Dominio de hechizos<\/em> pueden reemplazar parte del texto de las cartas o bien dar una habilidad adicional.<\/p>\n<p style=\"text-align: justify\">Adem\u00e1s, como un hechizo con <em>Dominio de\u00a0hechizos<\/em> comprueba su condici\u00f3n cuando se resuelve, es posible remover cartas del cementerio en respuesta, reduciendo su potencia a la hora de resolverse.<\/p>\n<p style=\"text-align: justify\">Cada carta con Dominio de hechizos es distinta, por lo que recuerda leerla bien para usarla correctamente.<\/p>\n<p>Escrito por Daniel Clarke, traducido por Nacho P\u00e9rez<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Bienvenidos! Hoy le daremos unas vueltas al Dominio de hechizos, una de las \u00a0nuevas mec\u00e1nicas de Or\u00edgenes. El hecho de que se encuentre escrito en cursiva ya nos indica algo: no significa nada durante una partida. Las &#8220;habilidades&#8221; escritas en cursiva son una forma de agrupar habilidades que hacen cosas parecidas o se disparan de [&hellip;]<\/p>\n","protected":false},"author":117,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[37],"tags":[412,413],"language":[],"class_list":["post-1486","post","type-post","status-publish","format-standard","hentry","category-palabras-clave","tag-dominio-de-hechizos","tag-spell-mastery"],"_links":{"self":[{"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/posts\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/comments?post=1486"}],"version-history":[{"count":5,"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/posts\/1486\/revisions"}],"predecessor-version":[{"id":1491,"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/posts\/1486\/revisions\/1491"}],"wp:attachment":[{"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/media?parent=1486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/categories?post=1486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/tags?post=1486"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/blogs.magicjudges.org\/rulestips-es\/wp-json\/wp\/v2\/language?post=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}